{"id":11768,"date":"2009-10-31T21:41:49","date_gmt":"2009-10-31T20:41:49","guid":{"rendered":"http:\/\/weli.at\/kinder\/?p=3"},"modified":"2016-01-06T16:19:29","modified_gmt":"2016-01-06T16:19:29","slug":"kinderwagen-fur-zwillinge","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/kinderwagen-fur-zwillinge\/","title":{"rendered":"Zwillingswagen oder Geschwisterwagen"},"content":{"rendered":"<p>Eine wichtige Entscheidung ist, ob die Kinder NEBENEINANDER oder HINTEREINANDER sitzen sollen!<\/p>\n<p>Die Kinder sitzen meist lieber nebeneinander.<!--more--><\/p>\n<ul>\n<li>Gewicht<\/li>\n<li>Preis<\/li>\n<li>Zubeh\u00f6r<\/li>\n<li>Ma\u00dfe<\/li>\n<li>Schadstoffe<\/li>\n<\/ul>\n<h2>Gewicht Geschwisterwagen<\/h2>\n<p>Der Wagen soll trotz seiner Gr\u00f6\u00dfe noch handlich und wendig sein. 10 bis 15 kg wiegt ein Zwillingswagen meist.<\/p>\n<h2>Preis Zwillingswagen<\/h2>\n<p>Auch sportliche Dreirad-Versionen (Jogger) sind mittlerweile Standard und auch leistbar &#8211; z.B. TFK, Quinny, Easy Walker. G\u00fcnstig ist ein Wagen von Zekiwa &#8211; NP um die 200,&#8211;.<br \/>\nSchn\u00e4ppchen bei Ebay sind keine Seltenheit!<\/p>\n<h2>Zubeh\u00f6r Geschwisterwagen<\/h2>\n<p>Zubeh\u00f6r &#8211; eine Tragetasche zum Beispiel &#8211; gibt es auch bei Amazon.<\/p>\n<h2>Ma\u00dfe Zwillingswagen<\/h2>\n<p>Im Normalfall passt der Wagen durch alle T\u00fcren mit Standardma\u00dfen &#8211; T\u00fcren bei Aufz\u00fcgen z.B. sind jedoch meist schmaler &#8211; also vor dem Kauf ausmessen! Mit diesen Ma\u00dfen geht sich fast alles aus:<br \/>\nAufgebaut: L\u00e4nge 106 cm x Breite 77 cm x H\u00f6he 110 cm<br \/>\nZusammengeklappt: L\u00e4nge 104 cm x Breite 77 cm x H\u00f6he 42 cm<br \/>\nSchieberh\u00f6he: 108<br \/>\nLiegefl\u00e4che: L\u00e4nge 84 cm x Breite 31 cm<br \/>\nIn Innsbruck ist es kein Problem mit einem Zwillingswagen in die Hungerburgbahn einzusteigen, bei M-Preis Andechsstra\u00dfe z.B. hat man jedoch Schwierigkeiten an der Kassa, bei M-Preis Sch\u00fctzenstra\u00dfe muss man das Drehkreuz verschieben um ins Gesch\u00e4ft zu gelangen, in die Hauptpost in der Salurner Stra\u00dfe kommt man gar nicht rein.<\/p>\n<h2>Schadstoffe Geschwisterwagen<\/h2>\n<p>Knokin-Kinderw\u00e4gen werden seit August 2004 nicht mehr produziert und es gibt nun auch keine Ersatzteile mehr! Wer Wert auf einen schadstoffarmen Kinderwagen legt, wird vielleicht bei naturkind-kinderwagen.de f\u00fcndig!<\/p>\n<div id=\"attachment_577\" style=\"width: 210px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.weli.at\/kinder\/wp-content\/uploads\/2009\/10\/IMG_4071.jpg\"><img aria-describedby=\"caption-attachment-577\" loading=\"lazy\" class=\"size-medium wp-image-577\" title=\"Zwillingswagen\" src=\"https:\/\/www.weli.at\/kinder\/wp-content\/uploads\/2009\/10\/IMG_4071-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" \/><\/a><p id=\"caption-attachment-577\" class=\"wp-caption-text\">Zwillingsjogger Zekiwa<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Breite,Hungerburgbahn,M-Preis,Hauptpost <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/kinderwagen-fur-zwillinge\/\">Zwillingswagen oder Geschwisterwagen<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[6,89],"tags":[],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/11768"}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=11768"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/11768\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=11768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=11768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=11768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}