{"id":1420,"date":"2010-12-01T22:03:51","date_gmt":"2010-12-01T21:03:51","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/?p=1420"},"modified":"2015-10-12T11:19:26","modified_gmt":"2015-10-12T11:19:26","slug":"baby-massage-kurs","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/baby-massage-kurs\/","title":{"rendered":"Schwangere Massage Kurs"},"content":{"rendered":"<p>Ein Kurs f\u00fcr Massage f\u00fcr Schwangere findet im Eltern-Kind-Zentrum in Innsbruck <!--more--><br \/>\nvom 4. bis 6. M\u00e4rz 2011 statt. Online Anmeldung ab 1. Feber 2011!<\/p>\n<h2>Baby &#8211; Schmetterlingsmassage f\u00fcr Schwangere in Innsbruck im Eltern-Kind-Zentrum:<\/h2>\n<p>Die sanfte Schmetterlingsmassage l\u00e4sst sich besonders gut in der Schwangerschaft, w\u00e4hrend der Geburt und bei Neugeborenen anwenden. K\u00f6rperspannungen k\u00f6nnen so behutsam gel\u00f6st werden.<\/p>\n<ul>\n<li>Termin Schmetterlingsmassage<\/li>\n<li>Kosten Schmetterlingsmassage<\/li>\n<li>Leitung Schmetterlingsmassage<\/li>\n<li>Themen Schmetterlingsmassage<\/li>\n<li>Telefonnummer EKIZ<\/li>\n<\/ul>\n<h2>Termine<\/h2>\n<p>Freitag, 4. M\u00e4rz 2011 bis Sonntag 6. M\u00e4rz 2011<\/p>\n<h2>Kosten<\/h2>\n<p>pro Person \u20ac 53,60, f\u00fcr Mitglieder \u20ac 48,20<\/p>\n<h2>Leitung<\/h2>\n<p>Maga. Marie-Luise Mitterberger &#8211; Kursleiterin f\u00fcr Schmetterlingsmassage, Hebamme, Erziehungswissenschaftlerin<br \/>\nMaga. Miriam Faber, Kursleiterin f\u00fcr Schmetterlingsmassage, EEH-Beraterin, Erziehungswissenschafterin<\/p>\n<h2>Themen<\/h2>\n<p>Massage, Spannungen l\u00f6sen &#8211; auch sehr geeignet f\u00fcr zuk\u00fcnftige Eltern von Zwillinge!<\/p>\n<h2>Telefonnummer f\u00fcr weitere Informationen<\/h2>\n<p>Eltern-Kind-Zentrum: 0043\/512\/58 19 97 Montag bis Freitag von 9 bis 18 Uhr<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Kurs f\u00fcr Massage f\u00fcr Schwangere findet im Eltern-Kind-Zentrum in Innsbruck <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/baby-massage-kurs\/\">Schwangere Massage Kurs<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[6,62,89],"tags":[119],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/1420"}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=1420"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/1420\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=1420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=1420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=1420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}