{"id":14314,"date":"2016-04-16T06:11:58","date_gmt":"2016-04-16T06:11:58","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/?p=14314"},"modified":"2016-04-20T17:36:36","modified_gmt":"2016-04-20T17:36:36","slug":"14314-2","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/14314-2\/","title":{"rendered":"Erziehung Vortrag Kindergarten"},"content":{"rendered":"<p><strong>&#8222;Wie sich n\u00f6rgeln, schimpfen und strafen vermeiden l\u00e4sst &#8211; Wege zum kompetenten Umgang mit kindlichem Problemverhalten&#8220;<\/strong><\/p>\n<p>Iris van den Hoeven, BA referiert rund um dieses Thema f\u00fcr die Altersspanne von 3-14 Jahren. Der Vortrag soll Eltern unterst\u00fctzen die Entwicklung ihrer Kinder besser zu verstehen, zu f\u00f6rdern und Verhaltensauff\u00e4lligkeiten vorzubeugen und entgegenzuwirken.<br \/>\n<!--more--><\/p>\n<p><strong>Schwerpunkte sind Fragen wie:<\/strong><\/p>\n<ul>\n<li>Wodurch entsteht problematisches Verhalten bei Kindern, was sind die h\u00e4ufigsten &#8222;Erziehungsfallen&#8220; und wie kann man diese umgehen?<\/li>\n<li>Welche M\u00f6glichkeiten gibt es, bereits eingespieltes Problemverhalten wieder aufzul\u00f6sen?<\/li>\n<li>Wie sieht kompetentes Handeln in schwierigen Situationen konkret aus?<\/li>\n<li>Welche Schritte m\u00fcssen gesetzt werden um von einer ersten Intervention zu einer langfristigen Probleml\u00f6sung zu gelangen?<\/li>\n<\/ul>\n<p>Viele wissenschaftlich fundierte Tipps, Tricks und Denkanst\u00f6\u00dfe verhelfen zu einer Erleichterung und Bereicherung des Erziehungsalltags.<\/p>\n<p><strong>Termine<\/strong><br \/>\nMontag, 18. April 2016, 19:30 Uhr im SH Wilten (Michael-Gaismair-Str. 4)<br \/>\nFreitag, 20. Mai 2016, 18:30 Uhr im SH H\u00f6tting-West (Franz-Baumann-Weg 10)<\/p>\n<p><strong>Kontakt<\/strong><br \/>\nB\u00fcrgerservice<br \/>\nKinderbetreuungseinrichtungen<br \/>\nMaria-Theresien-Stra\u00dfe 18<br \/>\n4. Stock<br \/>\nTelefon: +43 512 5360 4214<br \/>\nFax.: +43 512 5360 1736<br \/>\nChristina Wimmer Bachelor of Arts (BA) DW 4212<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Wie sich n\u00f6rgeln, schimpfen und strafen vermeiden l\u00e4sst &#8211; Wege zum kompetenten Umgang mit kindlichem Problemverhalten&#8220; Iris van den Hoeven, BA referiert rund um dieses Thema f\u00fcr die Altersspanne von 3-14 Jahren. Der Vortrag soll Eltern unterst\u00fctzen die Entwicklung ihrer Kinder besser zu verstehen, zu f\u00f6rdern und Verhaltensauff\u00e4lligkeiten vorzubeugen und entgegenzuwirken. <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/14314-2\/\">Erziehung Vortrag Kindergarten<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[10,12,21,81],"tags":[],"class_list":["post-14314","post","type-post","status-publish","format-standard","hentry","category-beratung","category-bildung","category-erziehung","category-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/14314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=14314"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/14314\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=14314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=14314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=14314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}