{"id":14505,"date":"2016-06-29T16:01:06","date_gmt":"2016-06-29T16:01:06","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/festung-ehrenberg\/"},"modified":"2016-06-29T16:01:07","modified_gmt":"2016-06-29T16:01:07","slug":"festung-ehrenberg-donnerstag-14-07","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/festung-ehrenberg-donnerstag-14-07\/","title":{"rendered":"FESTUNG EHRENBERG &#8211; Donnerstag, 14.07."},"content":{"rendered":"<p>Der Ferienzug wird im Raum Innsbuck, Tirol durchgef\u00fchrt. Es gibt Veranstaltungen f\u00fcr Kinder zu vielen spannenden Unternehmungen w\u00e4hrend der Ferien (falls Langweile aufkommt oder wenn Kinderbetreuung notwendig ist): Sport, Wissenschaft, Bewegung, Geschichte, Spannung, Kreativ, Technik, Natur und Outdoor,  etc<\/p>\n<p>Datum: Donnerstag, 14.07.2016<\/p>\n<p>\u00dcber die l\u00e4ngste H\u00e4ngebr\u00fccke der Alpen mit 408 m erobern wir das Fort Claudia der Festung Ehrenberg.<\/p>\n<p>Treffpunkt: 08.00 Uhr, RathausGalerien, Eingang Hotel Penz<br \/>\nDauer: 08.00 &#8211; 16.00 Uhr<br \/>\nAlter: 6 &#8211; 14 Jahre<\/p>\n<p>Ausr\u00fcstung:<br \/>\nKosten: \u0080 15,&#8211;<\/p>\n<h2>Geschichte f\u00fcr Kinder<\/h2>\n<p>Kategorie: Geschichte f\u00fcr Kinder<\/p>\n<p>Anmeldung: Kaspar Touristik, E-Mail: jarnika@gmx.at<br \/>\nQuelle: <a href=\"http:\/\/www.junges-innsbruck.at\/\" target=\"_blank\" rel=\"noopener\">Ferienzug Innsbruck<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Ferienzug wird im Raum Innsbuck, Tirol durchgef\u00fchrt. Es gibt Veranstaltungen f\u00fcr Kinder zu vielen spannenden Unternehmungen w\u00e4hrend der Ferien (falls Langweile aufkommt oder wenn Kinderbetreuung notwendig ist): Sport, Wissenschaft, Bewegung, Geschichte, Spannung, Kreativ, Technik, Natur und Outdoor, etc Datum: Donnerstag, 14.07.2016 \u00dcber die l\u00e4ngste H\u00e4ngebr\u00fccke der Alpen mit 408 m erobern wir das Fort&#8230; <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/festung-ehrenberg-donnerstag-14-07\/\">FESTUNG EHRENBERG 8211 Donnerstag<\/a> <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/festung-ehrenberg-donnerstag-14-07\/\">FESTUNG EHRENBERG 8211 Donnerstag<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[236,38],"tags":[],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/14505"}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=14505"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/14505\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=14505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=14505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=14505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}