{"id":2797,"date":"2012-04-06T17:33:25","date_gmt":"2012-04-06T15:33:25","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/?p=2797"},"modified":"2015-10-12T11:20:19","modified_gmt":"2015-10-12T11:20:19","slug":"sport-baby-kanga","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/sport-baby-kanga\/","title":{"rendered":"Sport Baby Kanga"},"content":{"rendered":"<p>Seit kurzer Zeit gibt es in Innsbruck ein neues Trainingsangebot f\u00fcr junge Mamas mit Babies! Es nennt sich Kanga Training und ist Europas gr\u00f6\u00dftes postnatale Workout!<!--more--><\/p>\n<h2>Kanga Trainierin<\/h2>\n<p>Heike Scherf ist die erste und bisher einzige Trainerin in Tirol und freut sich sehr \u00fcber den gro\u00dfen Zuspruch und das Interesse der Kursteilnehmerinnen und interessierte Mamas.<\/p>\n<p>Babies k\u00f6nnen im Tragetuch, Ergo Baby Carrier, und sehr h\u00e4ufig im Manduca (welcher auch ausgeliehen werden kann) an Kursen teilnehmen!<\/p>\n<h2>Kanga Termine<\/h2>\n<p>Start: Dienstag 20.03.2012<br \/>\n6020 &#8211; Innsbruck &#8211; Mitterweg 16<br \/>\n10:00 bis 11:00<br \/>\nausgebucht<\/p>\n<p>Start: Donnerstag 12.04.2012<br \/>\n6020 &#8211; Innsbruck &#8211; Andechstr. 65<br \/>\n9:00 bis 10:00<\/p>\n<p>Start: Dienstag 22.05.2012<br \/>\n6020 &#8211; Innsbruck &#8211; Mitterweg 16<br \/>\n10:00 bis 11:00<\/p>\n<h2>Kanga Kontakt<\/h2>\n<p>Heike Scherf<\/p>\n<p>Tropical Swing<\/p>\n<p>Pater Reinisch Weg 11a<\/p>\n<p>6020 Innsbruck<\/p>\n<p>Telefon +43 664 9202126<\/p>\n<p>heike@kangatraining.at<\/p>\n<p><a href=\"http:\/\/www.salsacongress.at\/\" target=\"_blank\" rel=\"noopener\">www.salsacongress.at<\/a><\/p>\n<p><a href=\"http:\/\/www.tropical-swing.com\/\" target=\"_blank\" rel=\"noopener\">www.tropical-swing.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit kurzer Zeit gibt es in Innsbruck ein neues Trainingsangebot f\u00fcr junge Mamas mit Babies! Es nennt sich Kanga Training und ist Europas gr\u00f6\u00dftes postnatale Workout! <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/sport-baby-kanga\/\">Sport Baby Kanga<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[6,11],"tags":[],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/2797"}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=2797"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/2797\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=2797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}