{"id":4997,"date":"2014-07-04T00:00:00","date_gmt":"2014-07-03T22:00:00","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/junge-uni\/4997"},"modified":"2015-10-10T11:58:03","modified_gmt":"2015-10-10T11:58:03","slug":"junge-uni","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/junge-uni\/","title":{"rendered":"Junge Uni"},"content":{"rendered":"<p>Datum: 15.07.14<\/p>\n<h2>Junge Uni<\/h2>\n<p>Junge Uni<br \/>\nChemie Mit-mach-ShowBist du Alchimist? Eine Sprengmeisterin? Ein Zauberer? Oder vielleicht einfach nur eine Wissenschaftlerin? Finde es heraus! Wann? Dienstag, 15.07. Treffpunkt? 08.45 Uhr, CCB Eingangsbereich, Innrain 80<br \/>\nDauer? 09.00 &#8211; 12.00 Uhr, Alter? 8 &#8211; 12 Jahre, Kostet? \u20ac 4,&#8211; Anmeldung? Junge Uni, http:\/\/jungeuni.uibk.ac.at<\/p>\n<p><a href=\"http:\/\/www.junges-innsbruck.at\/\" target=\"_blank\" rel=\"noopener\">Ferienzug Innsbruck<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datum: 15.07.14 Junge Uni Junge Uni Chemie Mit-mach-ShowBist du Alchimist? Eine Sprengmeisterin? Ein Zauberer? Oder vielleicht einfach nur eine Wissenschaftlerin? Finde es heraus! Wann? Dienstag, 15.07. Treffpunkt? 08.45 Uhr, CCB Eingangsbereich, Innrain 80 Dauer? 09.00 &#8211; 12.00 Uhr, Alter? 8 &#8211; 12 Jahre, Kostet? \u20ac 4,&#8211; Anmeldung? Junge Uni, http:\/\/jungeuni.uibk.ac.at Ferienzug Innsbruck <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/junge-uni\/\">Junge Uni<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26,78],"tags":[],"class_list":["post-4997","post","type-post","status-publish","format-standard","hentry","category-ferienzug-innsbruck","category-universitaet"],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/4997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=4997"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/4997\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=4997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=4997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=4997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}