{"id":5245,"date":"2014-07-31T07:45:01","date_gmt":"2014-07-31T05:45:01","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/zumba-kids\/5245"},"modified":"2015-10-10T11:57:24","modified_gmt":"2015-10-10T11:57:24","slug":"zumba-kids","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/zumba-kids\/","title":{"rendered":"Zumba Kids"},"content":{"rendered":"<p>Beim Ferienzug in Tirol gibt es folgende Veranstaltung f\u00fcr Kinder<\/p>\n<p>Datum: 23.07.14<\/p>\n<h2>Zumba Kids<\/h2>\n<p>Zumbatomic, das neue Fitnessprogramm f\u00fcr Kinder, ist ein rundum explosives und energiegeladenes Konzept, dass mit fr\u00f6hlich, fetziger Musik und coolen T\u00e4nzen auch die Faulsten vom Hocker rei\u00dft. Spa\u00df steht dabei im Vordergrund. <br \/>Wann? Mittwoch, 23.07. &#8211; Freitag, 25.07. <br \/>Treffpunkt? 11.00 Uhr, Volksschule Angergasse, Angergasse 20  <br \/>Dauer?  11.00 &#8211; 13.00 Uhr, <br \/>Alter? 6 &#8211; 11 Jahre<br \/>Ausr\u00fcstung? Turnbekleidung, <br \/>Kostet? \u20ac 19,&#8211; <br \/>Anmeldung? Dancing Unlimited, Tel. 0699\/11182362 oder E-Mail: welcome@dancingunlimited.at<\/p>\n<p><a href=\"http:\/\/www.junges-innsbruck.at\/\" target=\"_blank\" rel=\"noopener\">Ferienzug Innsbruck<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim Ferienzug in Tirol gibt es folgende Veranstaltung f\u00fcr Kinder Datum: 23.07.14 Zumba Kids Zumbatomic, das neue Fitnessprogramm f\u00fcr Kinder, ist ein rundum explosives und energiegeladenes Konzept, dass mit fr\u00f6hlich, fetziger Musik und coolen T\u00e4nzen auch die Faulsten vom Hocker rei\u00dft. Spa\u00df steht dabei im Vordergrund. Wann? Mittwoch, 23.07. &#8211; Freitag, 25.07. Treffpunkt? 11.00 Uhr,&#8230; <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/zumba-kids\/\">Zumba Kids<\/a> <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/zumba-kids\/\">Zumba Kids<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26,67],"tags":[],"class_list":["post-5245","post","type-post","status-publish","format-standard","hentry","category-ferienzug-innsbruck","category-sport"],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/5245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=5245"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/5245\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=5245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=5245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=5245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}