{"id":6367,"date":"2014-01-17T09:00:09","date_gmt":"2014-01-17T08:00:09","guid":{"rendered":"http:\/\/www.weli.at\/kinder\/dorfalm-cafe-restaurant\/6367"},"modified":"2015-10-10T12:03:38","modified_gmt":"2015-10-10T12:03:38","slug":"dorfalm-cafe-restaurant","status":"publish","type":"post","link":"https:\/\/www.weli.at\/kinder\/dorfalm-cafe-restaurant\/","title":{"rendered":"Dorfalm Cafe &#8211; Restaurant"},"content":{"rendered":"<h2>Dorfalm Cafe &#8211; Restaurant beim Tiroler Familienpass<\/h2>\n<p>Die Alm mitten im Dorf<\/p>\n<p>Bei Vorlage des Familienpasses vor der Bestellung gibt es bei jedem Erwachsenenhauptgericht, welches bis 16.30 Uhr bestellt ist, ein Kindergericht f\u00fcr ein am Familienpass eingetragenes Kind um Euro 1, &#8211; . Sie finden uns direkt an der Zufahrt zu den Fisser Bergbahnen. Es erwartet Sie ein urig, rustikales Lokal mit herrlicher Panoramaterrasse u. w\u00f6chentlichen Tagesspezialit\u00e4ten. Speziell f. Kinder haben wir Woodys Welt &#8211; einen gro\u00dfen, wetterunabh\u00e4ngigen Kinderspiel &#8211; u. Erlebnisbereich \u00fcber 2 Etagen! Hochstuhl Kinderspeisekarte Spielecke &#8211; Spielplatz Wickeltisch<\/p>\n<p>Kontakt <a href=\"mailto:\/\/office@dorfalm.at\" target=\"_blank\" rel=\"noopener\">office@dorfalm.at<\/a><br \/>\nTelefon: 0 54 76 &#8211; 60 20<br \/>\nSeilbahnstr. 20<br \/>\n6533 Fiss<br \/>\n<a href=\"http:\/\/www.dorfalm.at\" target=\"_blank\" rel=\"noopener\">Dorfalm Cafe &#8211; Restaurant<\/a><\/p>\n<p>Quelle: www.familienpass-tirol.at<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dorfalm Cafe &#8211; Restaurant beim Tiroler Familienpass Die Alm mitten im Dorf Bei Vorlage des Familienpasses vor der Bestellung gibt es bei jedem Erwachsenenhauptgericht, welches bis 16.30 Uhr bestellt ist, ein Kindergericht f\u00fcr ein am Familienpass eingetragenes Kind um Euro 1, &#8211; . Sie finden uns direkt an der Zufahrt zu den Fisser Bergbahnen. Es&#8230; <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/dorfalm-cafe-restaurant\/\">Dorfalm Cafe 8211 Restaurant<\/a> <a class=\"more-link\" href=\"https:\/\/www.weli.at\/kinder\/dorfalm-cafe-restaurant\/\">Dorfalm Cafe 8211 Restaurant<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[19,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/6367"}],"collection":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/comments?post=6367"}],"version-history":[{"count":0,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/posts\/6367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/media?parent=6367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/categories?post=6367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weli.at\/kinder\/wp-json\/wp\/v2\/tags?post=6367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}